{"id":4948,"date":"2020-03-19T21:13:59","date_gmt":"2020-03-19T20:13:59","guid":{"rendered":"http:\/\/www.mg-modelleisenbahnbau.de\/?post_type=product&#038;p=4948"},"modified":"2026-08-28T20:13:02","modified_gmt":"2026-08-28T18:13:02","slug":"4416-n-licht-ausfahrsignal-mit-vorsignal","status":"publish","type":"product","link":"https:\/\/www.mg-modelleisenbahnbau.de\/startseite-2\/produkt\/4416-n-licht-ausfahrsignal-mit-vorsignal\/","title":{"rendered":"4416 N Licht-Ausfahrsignal mit Vorsignal"},"content":{"rendered":"<div class=\"content--description\">\n<div class=\"content--title\">Produktinformationen &#8222;N Licht-Ausfahrsignal mit Vorsignal&#8220;<\/div>\n<div class=\"product--description\">Signal der Einheitsbauart. Filigraner Messingmast in originalgetreuer Lackierung. Patentsteckfu\u00df f\u00fcr einfache Montage. Mit 10 LEDs, wartungsfrei. Signalbilder Hp0, Hp0\/Sh1, Hp1, Hp2, Vr0, Vr1, Vr2. Passende Steuermodule: Art. 5220 und 5223. H\u00f6he: 4,4 cm.<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Produktinformationen &#8222;N Licht-Ausfahrsignal mit Vorsignal&#8220; Signal der Einheitsbauart. Filigraner Messingmast in originalgetreuer Lackierung. Patentsteckfu\u00df f\u00fcr einfache Montage. Mit 10 LEDs, wartungsfrei. Signalbilder Hp0, Hp0\/Sh1, Hp1, Hp2, Vr0, Vr1, Vr2. Passende Steuermodule: Art. 5220 und 5223. H\u00f6he: 4,4 cm.<\/p>\n","protected":false},"featured_media":4949,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[141,38,37,138],"product_tag":[292,291],"class_list":["post-4948","product","type-product","status-publish","has-post-thumbnail","product_cat-lichtsignale-n","product_cat-unkategorisiert","product_cat-viessmann","product_cat-viessmann-spur-n","product_tag-kein-spielzeug-nicht-geeignet-fuer-kinder-unter-14-jahren","product_tag-warn-und-sicherheitshinweise-modellbauartikel","first","instock","taxable","shipping-taxable","purchasable","product-type-simple","has-product-safety-information"],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.mg-modelleisenbahnbau.de\/startseite-2\/wp-json\/wp\/v2\/product\/4948","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.mg-modelleisenbahnbau.de\/startseite-2\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.mg-modelleisenbahnbau.de\/startseite-2\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/www.mg-modelleisenbahnbau.de\/startseite-2\/wp-json\/wp\/v2\/comments?post=4948"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.mg-modelleisenbahnbau.de\/startseite-2\/wp-json\/wp\/v2\/media\/4949"}],"wp:attachment":[{"href":"https:\/\/www.mg-modelleisenbahnbau.de\/startseite-2\/wp-json\/wp\/v2\/media?parent=4948"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.mg-modelleisenbahnbau.de\/startseite-2\/wp-json\/wp\/v2\/product_brand?post=4948"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.mg-modelleisenbahnbau.de\/startseite-2\/wp-json\/wp\/v2\/product_cat?post=4948"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.mg-modelleisenbahnbau.de\/startseite-2\/wp-json\/wp\/v2\/product_tag?post=4948"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}