{"id":3364,"date":"2019-08-20T13:57:15","date_gmt":"2019-08-20T11:57:15","guid":{"rendered":"http:\/\/www.mg-modelleisenbahnbau.de\/?post_type=product&#038;p=3364"},"modified":"2025-06-30T15:05:53","modified_gmt":"2025-06-30T13:05:53","slug":"38821-h0-schlossapotheke-und-antiquitaeten-in-toelz","status":"publish","type":"product","link":"https:\/\/www.mg-modelleisenbahnbau.de\/startseite-2\/produkt\/38821-h0-schlossapotheke-und-antiquitaeten-in-toelz\/","title":{"rendered":"38821 H0 Schlossapotheke und Antiquit\u00e4ten in T\u00f6lz"},"content":{"rendered":"<div class=\"content--description\">\n<div class=\"content--title\">Produktinformationen &#8222;H0 Schlossapotheke und Antiquit\u00e4ten in T\u00f6lz&#8220;<\/div>\n<div class=\"product--description\">Bausatz. Dieser Bausatz \u00e4hnelt den breitgelagerten H\u00e4usern der T\u00f6lzer Kaufleutefamilien und Patrizier im barocken Stil, welche allesamt mit Fassadenmalereien geschm\u00fcckt sind. Mit Stecksystem. Hergestellt im Zweifarben-Spritzgie\u00dfverfahren. Ma\u00dfe: L 20 x B 13,5 x H 12,5 cm. Schwierigkeitsgrad: 2 (Fortgeschrittene).<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Produktinformationen &#8222;H0 Schlossapotheke und Antiquit\u00e4ten in T\u00f6lz&#8220; Bausatz. Dieser Bausatz \u00e4hnelt den breitgelagerten H\u00e4usern der T\u00f6lzer Kaufleutefamilien und Patrizier im barocken Stil, welche allesamt mit Fassadenmalereien geschm\u00fcckt sind. Mit Stecksystem. Hergestellt im Zweifarben-Spritzgie\u00dfverfahren. Ma\u00dfe: L 20 x B 13,5 x H 12,5 cm. Schwierigkeitsgrad: 2 (Fortgeschrittene).<\/p>\n","protected":false},"featured_media":3365,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[216,44,201,38],"product_tag":[292,291],"class_list":["post-3364","product","type-product","status-publish","has-post-thumbnail","product_cat-alpenhaeuser-ho","product_cat-kibri","product_cat-kibri-spur-ho","product_cat-unkategorisiert","product_tag-kein-spielzeug-nicht-geeignet-fuer-kinder-unter-14-jahren","product_tag-warn-und-sicherheitshinweise-modellbauartikel","first","instock","taxable","shipping-taxable","purchasable","product-type-simple","has-product-safety-information"],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.mg-modelleisenbahnbau.de\/startseite-2\/wp-json\/wp\/v2\/product\/3364","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.mg-modelleisenbahnbau.de\/startseite-2\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.mg-modelleisenbahnbau.de\/startseite-2\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/www.mg-modelleisenbahnbau.de\/startseite-2\/wp-json\/wp\/v2\/comments?post=3364"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.mg-modelleisenbahnbau.de\/startseite-2\/wp-json\/wp\/v2\/media\/3365"}],"wp:attachment":[{"href":"https:\/\/www.mg-modelleisenbahnbau.de\/startseite-2\/wp-json\/wp\/v2\/media?parent=3364"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.mg-modelleisenbahnbau.de\/startseite-2\/wp-json\/wp\/v2\/product_brand?post=3364"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.mg-modelleisenbahnbau.de\/startseite-2\/wp-json\/wp\/v2\/product_cat?post=3364"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.mg-modelleisenbahnbau.de\/startseite-2\/wp-json\/wp\/v2\/product_tag?post=3364"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}